{"id":794,"date":"2024-08-23T05:36:34","date_gmt":"2024-08-23T05:36:34","guid":{"rendered":"https:\/\/diariodigitalcorrientes.com\/?p=794"},"modified":"2024-08-23T05:36:34","modified_gmt":"2024-08-23T05:36:34","slug":"patearon-todos-sus-penales-afuera-en-protesta-contra-el-var","status":"publish","type":"post","link":"https:\/\/diariodigitalcorrientes.com\/index.php\/2024\/08\/23\/patearon-todos-sus-penales-afuera-en-protesta-contra-el-var\/","title":{"rendered":"PATEARON TODOS SUS PENALES AFUERA EN PROTESTA CONTRA EL VAR"},"content":{"rendered":"\n<p>Caracas decidi\u00f3 ejecutar desviados los remates y su arquero se qued\u00f3 parado en los tiros del Deportivo T\u00e1chira. Fue para definir al campe\u00f3n de una copa amistosa<\/p>\n\n\n\n<p>El f\u00fatbol venezolano fue escenario de un hecho in\u00e9dito y pol\u00e9mico durante el cl\u00e1sico entre Deportivo T\u00e1chira y Caracas, disputado por la quinta jornada del Torneo Clausura. El partido, que termin\u00f3 1-1 en tiempo reglamentario, deriv\u00f3 en una tanda de penales que se llev\u00f3 a cabo de manera ins\u00f3lita como protesta por una decisi\u00f3n del VAR que gener\u00f3 controversia.<\/p>\n\n\n\n<p>Todo comenz\u00f3 en el minuto 99 del partido, cuando Caracas, que se hab\u00eda puesto en ventaja con un gol de Ender Echenique en la primera mitad, logr\u00f3 marcar el 2-1 a trav\u00e9s de Everardo Rose. Sin embargo, la celebraci\u00f3n fue breve, ya que la jueza asistente, Migdalia Rodr\u00edguez, levant\u00f3 su bandera se\u00f1alando fuera de juego. A pesar de que las repeticiones mostraban que Rose parec\u00eda estar habilitado, el VAR, a cargo de Reyes Soto y Jorge Urrego, confirm\u00f3 la posici\u00f3n adelantada. Como resultado, el \u00e1rbitro principal, Alexis Herrera, anul\u00f3 el gol y expuls\u00f3 a Rose por quitarse la camiseta en la celebraci\u00f3n.<\/p>\n\n\n\n<p>El empate en tiempo adicional del primer tiempo, logrado por Maurice Cova desde el punto penal tras una mano en el \u00e1rea sancionada por el VAR, dej\u00f3 el marcador igualado. Durante las protestas por la decisi\u00f3n arbitral, Renne Rivas, jugador de Caracas, fue expulsado por sus reclamos.<\/p>\n\n\n\n<p>Con el partido empatado y la &#8220;Copa Rey de Marcas&#8221; en juego, la tanda de penales se convirti\u00f3 en un escenario de protesta.<\/p>\n\n\n\n<p>Los jugadores de Caracas decidieron ejecutar sus remates intencionalmente desviados, mientras que su arquero, Frankarlos Ben\u00edtez, permaneci\u00f3 inm\u00f3vil en los tiros del rival. Carlos Vivas anot\u00f3 el primer penal para T\u00e1chira, mientras que Luis Casiani, de Caracas, tir\u00f3 deliberadamente su disparo fuera. Lo mismo ocurri\u00f3 con Anderson Contreras y N\u00e9stor Jim\u00e9nez, quienes tambi\u00e9n remataron desviados.<\/p>\n\n\n\n<p>Los espectadores pronto comprendieron que se trataba de una protesta contra la decisi\u00f3n del VAR, lo que desat\u00f3 la indignaci\u00f3n en las gradas, desde donde se escucharon gritos de desaprobaci\u00f3n. El espect\u00e1culo qued\u00f3 empa\u00f1ado por esta singular protesta, dejando una imagen negativa del encuentro.<\/p>\n\n\n\n<p>Con el empate en tiempo reglamentario, Deportivo T\u00e1chira mantuvo el liderazgo del torneo con 11 puntos, mientras que Caracas, con 5 unidades, sigue fuera de la zona de clasificaci\u00f3n al cuadrangular final. Migdalia Rodr\u00edguez, la jueza asistente que anul\u00f3 el gol de Rose, acompa\u00f1ar\u00e1 a su compatriota Yender Herrera en la final de la Intercontinental Sub-20 que se disputar\u00e1 este s\u00e1bado entre Flamengo y Olympiacos en R\u00edo de Janeiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caracas decidi\u00f3 ejecutar desviados los remates y su arquero se qued\u00f3 parado en los tiros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/794"}],"collection":[{"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=794"}],"version-history":[{"count":1,"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/794\/revisions"}],"predecessor-version":[{"id":796,"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/794\/revisions\/796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/795"}],"wp:attachment":[{"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodigitalcorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}